{"id":6621,"date":"2021-01-06T21:16:00","date_gmt":"2021-01-06T21:16:00","guid":{"rendered":"https:\/\/bg2v.com\/bg2v-apporte-son-soutien-a-la-randonnee-caritative-des-cycles-de-limmobilier\/"},"modified":"2023-12-11T08:58:19","modified_gmt":"2023-12-11T08:58:19","slug":"bg2v-supports-the-cycles-de-limmobilier-charity-ride","status":"publish","type":"post","link":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/","title":{"rendered":"BG2V supports the Cycles de l\u2019Immobilier Charity Ride"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bottom_padding=&#8221;2%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;6618&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text el_class=&#8221;med&#8221;]For the first year, BG2V is supporting the Cycles de l\u2019Immobilier Charity Ride, which will take place from June 3 to 7, 2021 during MIPIM 2021.<br \/>\nThe synergies developed with the other sponsors and partners will allow BG2V to become even more committed to the charities supported by the Cycles de l\u2019Immobilier.[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;2%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;large&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;see-through-2&#8243; color_override=&#8221;#000000&#8243; hover_color_override=&#8221;#0a0a0a&#8221; hover_text_color_override=&#8221;#ffffff&#8221; icon_family=&#8221;iconsmind&#8221; text=&#8221;Web site&#8221; url=&#8221;https:\/\/www.lescyclesdelimmobilier.org\/&#8221; icon_iconsmind=&#8221;iconsmind-File-Network&#8221;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]","protected":false},"excerpt":{"rendered":"<p>Janvier 2021<\/p>","protected":false},"author":1,"featured_media":6619,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[],"class_list":["post-6621","post","type-post","status-publish","format-standard","has-post-thumbnail","category-events-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BG2V supports the Cycles de l\u2019Immobilier Charity Ride - BG2V\u00a0Avocats<\/title>\n<meta name=\"description\" content=\"BG2V is supporting the Cycles de l\u2019Immobilier Charity Ride, which will take place from June 3 to 7, 2021 during MIPIM 2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BG2V supports the Cycles de l\u2019Immobilier Charity Ride - BG2V\u00a0Avocats\" \/>\n<meta property=\"og:description\" content=\"BG2V is supporting the Cycles de l\u2019Immobilier Charity Ride, which will take place from June 3 to 7, 2021 during MIPIM 2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/\" \/>\n<meta property=\"og:site_name\" content=\"BG2V\u00a0Avocats\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-06T21:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-11T08:58:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bg2v.com\/wp-content\/uploads\/2021\/01\/les-cycles-de-immobilier.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"bg2vadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"bg2vadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/\"},\"author\":{\"name\":\"bg2vadmin\",\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/#\\\/schema\\\/person\\\/b7104b949c614174feb80371f4f63ad9\"},\"headline\":\"BG2V supports the Cycles de l\u2019Immobilier Charity Ride\",\"datePublished\":\"2021-01-06T21:16:00+00:00\",\"dateModified\":\"2023-12-11T08:58:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/\"},\"wordCount\":1308,\"publisher\":{\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bg2v.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/les-cycles-de-immobilier.jpg\",\"articleSection\":[\"Events\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/\",\"url\":\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/\",\"name\":\"BG2V supports the Cycles de l\u2019Immobilier Charity Ride - BG2V\u00a0Avocats\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bg2v.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/les-cycles-de-immobilier.jpg\",\"datePublished\":\"2021-01-06T21:16:00+00:00\",\"dateModified\":\"2023-12-11T08:58:19+00:00\",\"description\":\"BG2V is supporting the Cycles de l\u2019Immobilier Charity Ride, which will take place from June 3 to 7, 2021 during MIPIM 2021.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bg2v.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/les-cycles-de-immobilier.jpg\",\"contentUrl\":\"https:\\\/\\\/bg2v.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/les-cycles-de-immobilier.jpg\",\"width\":500,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/bg2v.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BG2V supports the Cycles de l\u2019Immobilier Charity Ride\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/bg2v.com\\\/en\\\/\",\"name\":\"BG2V\u00a0Avocats Associ\u00e9s\",\"description\":\"Cr\u00e9ateurs de solutions pour vos enjeux juridiques et \u00e9conomiques\",\"publisher\":{\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bg2v.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/#organization\",\"name\":\"BG2V\u00a0Avocats Associ\u00e9s\",\"url\":\"https:\\\/\\\/bg2v.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bg2v.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/bg2v-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/bg2v.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/bg2v-logo.jpg\",\"width\":500,\"height\":500,\"caption\":\"BG2V\u00a0Avocats Associ\u00e9s\"},\"image\":{\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bg2v.com\\\/en\\\/#\\\/schema\\\/person\\\/b7104b949c614174feb80371f4f63ad9\",\"name\":\"bg2vadmin\",\"sameAs\":[\"https:\\\/\\\/bg2v.com\"],\"url\":\"https:\\\/\\\/bg2v.com\\\/en\\\/author\\\/bg2vadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BG2V supports the Cycles de l\u2019Immobilier Charity Ride - BG2V\u00a0Avocats","description":"BG2V is supporting the Cycles de l\u2019Immobilier Charity Ride, which will take place from June 3 to 7, 2021 during MIPIM 2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/","og_locale":"en_US","og_type":"article","og_title":"BG2V supports the Cycles de l\u2019Immobilier Charity Ride - BG2V\u00a0Avocats","og_description":"BG2V is supporting the Cycles de l\u2019Immobilier Charity Ride, which will take place from June 3 to 7, 2021 during MIPIM 2021.","og_url":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/","og_site_name":"BG2V\u00a0Avocats","article_published_time":"2021-01-06T21:16:00+00:00","article_modified_time":"2023-12-11T08:58:19+00:00","og_image":[{"width":500,"height":200,"url":"https:\/\/bg2v.com\/wp-content\/uploads\/2021\/01\/les-cycles-de-immobilier.jpg","type":"image\/jpeg"}],"author":"bg2vadmin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"bg2vadmin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/#article","isPartOf":{"@id":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/"},"author":{"name":"bg2vadmin","@id":"https:\/\/bg2v.com\/en\/#\/schema\/person\/b7104b949c614174feb80371f4f63ad9"},"headline":"BG2V supports the Cycles de l\u2019Immobilier Charity Ride","datePublished":"2021-01-06T21:16:00+00:00","dateModified":"2023-12-11T08:58:19+00:00","mainEntityOfPage":{"@id":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/"},"wordCount":1308,"publisher":{"@id":"https:\/\/bg2v.com\/en\/#organization"},"image":{"@id":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/#primaryimage"},"thumbnailUrl":"https:\/\/bg2v.com\/wp-content\/uploads\/2021\/01\/les-cycles-de-immobilier.jpg","articleSection":["Events"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/","url":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/","name":"BG2V supports the Cycles de l\u2019Immobilier Charity Ride - BG2V\u00a0Avocats","isPartOf":{"@id":"https:\/\/bg2v.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/#primaryimage"},"image":{"@id":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/#primaryimage"},"thumbnailUrl":"https:\/\/bg2v.com\/wp-content\/uploads\/2021\/01\/les-cycles-de-immobilier.jpg","datePublished":"2021-01-06T21:16:00+00:00","dateModified":"2023-12-11T08:58:19+00:00","description":"BG2V is supporting the Cycles de l\u2019Immobilier Charity Ride, which will take place from June 3 to 7, 2021 during MIPIM 2021.","breadcrumb":{"@id":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/#primaryimage","url":"https:\/\/bg2v.com\/wp-content\/uploads\/2021\/01\/les-cycles-de-immobilier.jpg","contentUrl":"https:\/\/bg2v.com\/wp-content\/uploads\/2021\/01\/les-cycles-de-immobilier.jpg","width":500,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/bg2v.com\/en\/bg2v-supports-the-cycles-de-limmobilier-charity-ride\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/bg2v.com\/en\/"},{"@type":"ListItem","position":2,"name":"BG2V supports the Cycles de l\u2019Immobilier Charity Ride"}]},{"@type":"WebSite","@id":"https:\/\/bg2v.com\/en\/#website","url":"https:\/\/bg2v.com\/en\/","name":"BG2V\u00a0Avocats Associ\u00e9s","description":"Cr\u00e9ateurs de solutions pour vos enjeux juridiques et \u00e9conomiques","publisher":{"@id":"https:\/\/bg2v.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bg2v.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bg2v.com\/en\/#organization","name":"BG2V\u00a0Avocats Associ\u00e9s","url":"https:\/\/bg2v.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bg2v.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/bg2v.com\/wp-content\/uploads\/2024\/07\/bg2v-logo.jpg","contentUrl":"https:\/\/bg2v.com\/wp-content\/uploads\/2024\/07\/bg2v-logo.jpg","width":500,"height":500,"caption":"BG2V\u00a0Avocats Associ\u00e9s"},"image":{"@id":"https:\/\/bg2v.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/bg2v.com\/en\/#\/schema\/person\/b7104b949c614174feb80371f4f63ad9","name":"bg2vadmin","sameAs":["https:\/\/bg2v.com"],"url":"https:\/\/bg2v.com\/en\/author\/bg2vadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/bg2v.com\/en\/wp-json\/wp\/v2\/posts\/6621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bg2v.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bg2v.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bg2v.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bg2v.com\/en\/wp-json\/wp\/v2\/comments?post=6621"}],"version-history":[{"count":2,"href":"https:\/\/bg2v.com\/en\/wp-json\/wp\/v2\/posts\/6621\/revisions"}],"predecessor-version":[{"id":6623,"href":"https:\/\/bg2v.com\/en\/wp-json\/wp\/v2\/posts\/6621\/revisions\/6623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bg2v.com\/en\/wp-json\/wp\/v2\/media\/6619"}],"wp:attachment":[{"href":"https:\/\/bg2v.com\/en\/wp-json\/wp\/v2\/media?parent=6621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bg2v.com\/en\/wp-json\/wp\/v2\/categories?post=6621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bg2v.com\/en\/wp-json\/wp\/v2\/tags?post=6621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}